{"id":114,"date":"2018-09-29T12:08:03","date_gmt":"2018-09-29T15:08:03","guid":{"rendered":"http:\/\/eventos.cmm.uchile.cl\/emic2018\/?page_id=114"},"modified":"2018-11-15T17:39:18","modified_gmt":"2018-11-15T20:39:18","slug":"lugar","status":"publish","type":"page","link":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/lugar\/","title":{"rendered":"Lugar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":56,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-114","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/pages\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/comments?post=114"}],"version-history":[{"count":1,"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/pages\/114\/revisions"}],"predecessor-version":[{"id":126,"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/pages\/114\/revisions\/126"}],"wp:attachment":[{"href":"https:\/\/eventos.cmm.uchile.cl\/emic2018\/wp-json\/wp\/v2\/media?parent=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}